{"id":3817,"date":"2011-03-03T17:07:07","date_gmt":"2011-03-03T16:07:07","guid":{"rendered":"http:\/\/www.plotmag.com\/blog\/?p=3817"},"modified":"2017-09-04T10:22:51","modified_gmt":"2017-09-04T08:22:51","slug":"mediafacade","status":"publish","type":"post","link":"https:\/\/www.plotmag.com\/blog\/2011\/03\/mediafacade\/","title":{"rendered":"Mediafacade"},"content":{"rendered":"<p>Onlyglass Mediafacade ist die erste digitale Medienfassade, die in die Architektur selbst integriert wird. Hierbei ersetzt sie herk\u00f6mmliche Verglasungssysteme, indem die Funktionen von LED-Monitor und Isolierverglasung in diesem neuartigen Medium verschmelzen.<br \/>\nIn Abh\u00e4ngigkeit vom gew\u00e4hlten Pixelabstand ab 20 Millimetern bei grenzenloser Skalierbarkeit l\u00e4sst sich eine Lichttransparenz zwischen 80 und 96 Prozent erzielen. Im Verbund mit den rund 1 Milliarde darstellbaren Farben (10 bit) ist die MEDIAFACADE zur Zeit das leistungsf\u00e4higste Display unter allen transparenten Medienfassaden. An der Nahtstelle zwischen Innen- und Au\u00dfenraum installiert, bietet das neue Medium ungeahnte Inszenierungsm\u00f6glichkeiten. Je nach Anforderung changiert die Geb\u00e4udefassade zwischen Gro\u00dfdisplay und Schaufenster.<br \/>\nAufgrund des geringen Zusatzgewichts ist der Einbau nicht nur bei neu errichteten Geb\u00e4uden aus statischer Sicht zumeist v\u00f6llig unbedenklich, sondern auch dort, wo bei der Modernisierung \u00e4lterer Bauten Belange des Denkmalschutzes ber\u00fchrt sind.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Onlyglass Mediafacade ist die erste digitale Medienfassade, die in die Architektur selbst integriert wird. Hierbei ersetzt sie herk\u00f6mmliche Verglasungssysteme, indem die Funktionen von LED-Monitor [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[10],"tags":[125,375],"_links":{"self":[{"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/posts\/3817"}],"collection":[{"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/comments?post=3817"}],"version-history":[{"count":6,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/posts\/3817\/revisions"}],"predecessor-version":[{"id":22452,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/posts\/3817\/revisions\/22452"}],"wp:attachment":[{"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/media?parent=3817"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/categories?post=3817"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/tags?post=3817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}