{"id":28732,"date":"2016-10-10T09:14:23","date_gmt":"2016-10-10T09:14:23","guid":{"rendered":"http:\/\/www.plotmag.com\/blog\/?p=19896"},"modified":"2017-04-03T11:55:03","modified_gmt":"2017-04-03T09:55:03","slug":"de-sede","status":"publish","type":"post","link":"https:\/\/www.plotmag.com\/blog\/2016\/10\/de-sede\/","title":{"rendered":"de Sede"},"content":{"rendered":"<p>Anl\u00e4sslich des 50-j\u00e4hrigen Jubil\u00e4ums des M\u00f6bel-Herstellers de Sede, der 1965 aus einem kleinen Sattlerbetrieb hervorging, entwickelte das Stuttgarter Design Studio Projekttriangle nicht nur eine neue visuelle Identit\u00e4t, sondern gestaltete zudem einen schlichten, aber imposanten Markenauftritt f\u00fcr die internationalen M\u00f6belmessen in K\u00f6ln und Mailand. Um dem Hersteller seine urspr\u00fcngliche Strahlkraft als exklusive, internationale Sitzm\u00f6belmanufaktur zur\u00fcckzugeben, entwarf das Gestalter-Trio Djokic, Grothmaak und Sp\u00e4th im ersten Schritt ein neues Markenleitbild. Um dieses formulieren zu k\u00f6nnen wurde der Kern \u2013 das \u201eEigene\u201c \u2013 der Marke gezielt herausgearbeitet.<\/p>\n<p>Auf diesem Vorgehen aufbauend, st\u00fctzt sich die gesamte visuelle Markeninszenierung nun auf die imposanten Schweizer Alpen, in deren landschaftlicher Kulisse die M\u00f6bel von de Sede entworfen und hergestellt werden. Martin Grothmaaks Fotografien von Bergmassiven spiegeln dabei die Werte, die sich in der Qualit\u00e4t der handgefertigten Lederm\u00f6bel wiederfinden: Tradition, Innovation sowie der Bezug zu inspirierenden R\u00e4umen und Orten. Dadurch wird zudem die Unternehmensphilosophie aufgegriffen, \u201eOrte kraftvoller werden zu lassen [\u2026] und dabei die Individualit\u00e4t des Menschen gezielt herauszuheben\u201c. Als gro\u00dfformatige wandf\u00fcllende Drucke bieten die Bergaufnahmen somit eine beeindruckende und gleichzeitig hintersinnige Kulisse f\u00fcr die einzelnen Ausstellungsst\u00fccke. In Kooperation mit den Frankfurter Architekten Hollin+Radoske entstand erg\u00e4nzend dazu ein durchdachtes Raum-im-Raum-Konzept aus reduzierten Kuben, in denen die verschiedenen Sitzm\u00f6bel-Programme vor der Alpenkulisse begutachtet werden k\u00f6nnen. Der variable Aufbau erm\u00f6glicht dabei den wiederholten Einsatz, sowohl zur Inszenierung wechselnder Exponate, als auch zur Schaffung einer einpr\u00e4gsamen Umgebung f\u00fcr die Messebesucher. Um letzteres weiter zu verst\u00e4rken, wurden die Fotografien ebenfalls im Neuheiten-Katalog sowie auf der Website verwendet. So ist das Markenleitbild stets pr\u00e4sent und es entsteht eine umfassende, den Messekontakt \u00fcbersteigende visuelle Inszenierung mit majest\u00e4tisch-alpinem Charakter.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anl\u00e4sslich des 50-j\u00e4hrigen Jubil\u00e4ums des M\u00f6bel-Herstellers de Sede, der 1965 aus einem kleinen Sattlerbetrieb hervorging, entwickelte das Stuttgarter Design Studio Projekttriangle nicht nur eine [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[40,52,1530],"_links":{"self":[{"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/posts\/28732"}],"collection":[{"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/comments?post=28732"}],"version-history":[{"count":6,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/posts\/28732\/revisions"}],"predecessor-version":[{"id":28746,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/posts\/28732\/revisions\/28746"}],"wp:attachment":[{"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/media?parent=28732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/categories?post=28732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/tags?post=28732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}