{"id":19747,"date":"2014-07-03T15:53:38","date_gmt":"2014-07-03T13:53:38","guid":{"rendered":"http:\/\/www.plotmag.com\/blog\/?p=19747"},"modified":"2016-03-07T09:22:49","modified_gmt":"2016-03-07T08:22:49","slug":"im-goldenen-schnitt","status":"publish","type":"post","link":"https:\/\/www.plotmag.com\/blog\/2014\/07\/im-goldenen-schnitt\/","title":{"rendered":"Im Goldenen Schnitt"},"content":{"rendered":"<p><strong>Im Goldenen Schnitt &#8211; Niedersachsens l\u00e4ngste Ausgrabung<\/strong><\/p>\n<p>Der Bau der Nordeurop\u00e4ischen Erdgas-Leitung (NEL) von Lubmin an der Ostseek\u00fcste quer durch Norddeutschland bis nach Rehden im Landkreis Diepholz 2011-2012 wurde zur Goldgrube im wahrsten Sinne des Wortes. Die Trasse bildete mit 200 km den l\u00e4ngsten arch\u00e4ologischen Grabungsschnitt, den es je in Niedersachsen gab. H\u00f6hepunkt der zahlreichen Funde ist der mehr als 3000 Jahre alte Goldschatz von Gessel. Er ist das Kernst\u00fcck der Ausstellung \u201eIm Goldenen Schnitt \u2013 Niedersachsens l\u00e4ngste Ausgrabung\u201c.<\/p>\n<p>Nachdem der Besucher durch eine inszenierte Pipeline die Ausstellung betreten hat, kann er sich auf dem stilisierten \u201eGrabungsfeld\u201c an acht Multimedia-Stationen \u00fcber die Fundpl\u00e4tze und ihre wissenschaftliche Aufarbeitung informieren. Er gelangt dann vorbei an einem scheinbar unter Wasser pr\u00e4sentierten Fund aus der im Greifswalder Bodden gesunkenen Kogge in den glutroten Themenkomplex der Metallverarbeitung. Schlie\u00dflich erreicht er im d\u00e4mmrigen Licht den mattgoldenen, polygonalen Hort des schimmernden Schatzes.<\/p>\n<p>Die Ausstellung pr\u00e4sentiert die historisch einzigartigen Funde und macht den fr\u00fchgeschichtlichen Rohstoffim- und \u2013\/export sowie seine Erforschung fassbar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Goldenen Schnitt &#8211; Niedersachsens l\u00e4ngste Ausgrabung Der Bau der Nordeurop\u00e4ischen Erdgas-Leitung (NEL) von Lubmin an der Ostseek\u00fcste quer durch Norddeutschland bis nach Rehden [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[284,1024],"_links":{"self":[{"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/posts\/19747"}],"collection":[{"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/comments?post=19747"}],"version-history":[{"count":4,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/posts\/19747\/revisions"}],"predecessor-version":[{"id":22175,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/posts\/19747\/revisions\/22175"}],"wp:attachment":[{"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/media?parent=19747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/categories?post=19747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.plotmag.com\/blog\/wp-json\/wp\/v2\/tags?post=19747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}